{"id":9,"count":64,"description":"","link":"https:\/\/ensemble.cymru\/cy\/categori\/newyddion\/","name":"Newyddion","slug":"newyddion","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Newyddion Archives - Ensemble Cymru<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ensemble.cymru\/cy\/categori\/newyddion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Newyddion Archives - Ensemble Cymru\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ensemble.cymru\/cy\/categori\/newyddion\/\" \/>\n<meta property=\"og:site_name\" content=\"Ensemble Cymru\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EnsCymru\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ensemble.cymru\\\/cy\\\/categori\\\/newyddion\\\/\",\"url\":\"https:\\\/\\\/ensemble.cymru\\\/cy\\\/categori\\\/newyddion\\\/\",\"name\":\"Newyddion Archives - Ensemble Cymru\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ensemble.cymru\\\/cy\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ensemble.cymru\\\/cy\\\/categori\\\/newyddion\\\/#breadcrumb\"},\"inLanguage\":\"cy\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ensemble.cymru\\\/cy\\\/categori\\\/newyddion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ensemble.cymru\\\/cy\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Newyddion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ensemble.cymru\\\/cy\\\/#website\",\"url\":\"https:\\\/\\\/ensemble.cymru\\\/cy\\\/\",\"name\":\"Ensemble Cymru\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ensemble.cymru\\\/cy\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ensemble.cymru\\\/cy\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cy\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ensemble.cymru\\\/cy\\\/#organization\",\"name\":\"Ensemble Cymru\",\"url\":\"https:\\\/\\\/ensemble.cymru\\\/cy\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cy\",\"@id\":\"https:\\\/\\\/ensemble.cymru\\\/cy\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ensemble.cymru\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/2019-09-02EnsembleSquareLogo.png\",\"contentUrl\":\"https:\\\/\\\/ensemble.cymru\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/2019-09-02EnsembleSquareLogo.png\",\"width\":320,\"height\":320,\"caption\":\"Ensemble Cymru\"},\"image\":{\"@id\":\"https:\\\/\\\/ensemble.cymru\\\/cy\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EnsCymru\\\/\",\"https:\\\/\\\/x.com\\\/EnsCymru\",\"https:\\\/\\\/www.instagram.com\\\/enscymru\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Newyddion Archives - Ensemble Cymru","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ensemble.cymru\/cy\/categori\/newyddion\/","og_locale":"en_US","og_type":"article","og_title":"Newyddion Archives - Ensemble Cymru","og_url":"https:\/\/ensemble.cymru\/cy\/categori\/newyddion\/","og_site_name":"Ensemble Cymru","twitter_card":"summary_large_image","twitter_site":"@EnsCymru","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ensemble.cymru\/cy\/categori\/newyddion\/","url":"https:\/\/ensemble.cymru\/cy\/categori\/newyddion\/","name":"Newyddion Archives - Ensemble Cymru","isPartOf":{"@id":"https:\/\/ensemble.cymru\/cy\/#website"},"breadcrumb":{"@id":"https:\/\/ensemble.cymru\/cy\/categori\/newyddion\/#breadcrumb"},"inLanguage":"cy"},{"@type":"BreadcrumbList","@id":"https:\/\/ensemble.cymru\/cy\/categori\/newyddion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ensemble.cymru\/cy\/"},{"@type":"ListItem","position":2,"name":"Newyddion"}]},{"@type":"WebSite","@id":"https:\/\/ensemble.cymru\/cy\/#website","url":"https:\/\/ensemble.cymru\/cy\/","name":"Ensemble Cymru","description":"","publisher":{"@id":"https:\/\/ensemble.cymru\/cy\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ensemble.cymru\/cy\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cy"},{"@type":"Organization","@id":"https:\/\/ensemble.cymru\/cy\/#organization","name":"Ensemble Cymru","url":"https:\/\/ensemble.cymru\/cy\/","logo":{"@type":"ImageObject","inLanguage":"cy","@id":"https:\/\/ensemble.cymru\/cy\/#\/schema\/logo\/image\/","url":"https:\/\/ensemble.cymru\/wp-content\/uploads\/2024\/08\/2019-09-02EnsembleSquareLogo.png","contentUrl":"https:\/\/ensemble.cymru\/wp-content\/uploads\/2024\/08\/2019-09-02EnsembleSquareLogo.png","width":320,"height":320,"caption":"Ensemble Cymru"},"image":{"@id":"https:\/\/ensemble.cymru\/cy\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EnsCymru\/","https:\/\/x.com\/EnsCymru","https:\/\/www.instagram.com\/enscymru"]}]}},"_links":{"self":[{"href":"https:\/\/ensemble.cymru\/cy\/wp-json\/wp\/v2\/categories\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ensemble.cymru\/cy\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/ensemble.cymru\/cy\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/ensemble.cymru\/cy\/wp-json\/wp\/v2\/posts?categories=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}